{"id":5319,"date":"2024-11-13T15:00:00","date_gmt":"2024-11-13T18:00:00","guid":{"rendered":"https:\/\/iigual.com.br\/blog\/?p=5319"},"modified":"2024-11-24T13:45:02","modified_gmt":"2024-11-24T16:45:02","slug":"eu-parei-de-andar-e-aprendi-a-voar","status":"publish","type":"post","link":"https:\/\/iigual.com.br\/blog\/eu-parei-de-andar-e-aprendi-a-voar\/","title":{"rendered":"Parei de Andar e Aprendi a Voar: uma jornada de supera\u00e7\u00e3o e inspira\u00e7\u00e3o"},"content":{"rendered":"\n<p>Em sua biografia &#8220;<strong>Eu Parei de Andar e Aprendi a Voar<\/strong>&#8220;, <a href=\"https:\/\/iigual.com.br\/blog\/andrea-schwarz-historia\/\" target=\"_blank\" rel=\"noreferrer noopener\">Andrea Schwarz<\/a>, um exemplo vivo de como transformar adversidades em asas para voar mais alto, revela sua jornada de desafios e descobertas ap\u00f3s tornar-se cadeirante aos 22 anos.\u00a0<\/p>\n\n\n\n<p>Esta obra inspiradora explora os temas de supera\u00e7\u00e3o, bem como, aceita\u00e7\u00e3o, inclus\u00e3o, prop\u00f3sito e empreendedorismo, refletindo o impacto de suas a\u00e7\u00f5es na sociedade e no mundo corporativo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quem \u00e9 Andrea Schwarz, autora do livro &#8220;Eu Parei de Andar e Aprendi a Voar\u201d?<\/h2>\n\n\n\n<p>Andrea Schwarz \u00e9 uma figura de destaque no cen\u00e1rio de inclus\u00e3o e diversidade. Aos 22 anos, sua vida tomou um rumo inesperado quando uma condi\u00e7\u00e3o cong\u00eanita na medula a tornou cadeirante.&nbsp;<\/p>\n\n\n\n<p>Esse desafio, no entanto, n\u00e3o a impediu de avan\u00e7ar em seus sonhos e objetivos. Com determina\u00e7\u00e3o, ela se tornou empres\u00e1ria e fundadora da iigual, uma consultoria que conecta pessoas com defici\u00eancia ao mercado de trabalho.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como Andrea Schwarz transformou adversidades em impulsos de supera\u00e7\u00e3o?<\/h2>\n\n\n\n<p>Ap\u00f3s enfrentar in\u00fameras barreiras de acessibilidade em suas viagens e atividades do dia a dia, Andrea viu uma oportunidade de transformar sua experi\u00eancia pessoal em a\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Por isso, o seu trabalho foca na inclus\u00e3o de pessoas com defici\u00eancia no mercado de trabalho.&nbsp;<\/p>\n\n\n\n<p>Essa vis\u00e3o englobou a funda\u00e7\u00e3o da iigual, que impacta tanto empresas quanto pessoas com defici\u00eancia, facilitando, ent\u00e3o, a inclus\u00e3o dessas no mercado de trabalho.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">O papel da iigual no mercado<\/h3>\n\n\n\n<p>A iigual se destaca como uma das principais consultorias que promovem a diversidade e a inclus\u00e3o de pessoas com defici\u00eancia no Brasil. Desse modo, ela auxilia empresas a estruturarem programas de contrata\u00e7\u00e3o inclusiva e adaptarem seus espa\u00e7os e pol\u00edticas para serem mais acolhedores.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quais s\u00e3o as conquistas e reconhecimentos da autora de &#8220;Eu Parei de Andar e Aprendi a Voar\u201d?<\/h2>\n\n\n\n<p>O impacto de Andrea Schwarz vai al\u00e9m de suas realiza\u00e7\u00f5es empresariais. Sua presen\u00e7a influente em plataformas como Instagram, TikTok e LinkedIn alcan\u00e7a mais de 1 milh\u00e3o de pessoas.&nbsp;<\/p>\n\n\n\n<p>Em 2021, 2022, 2023 e 2024, ela foi reconhecida pela Bloomberg L\u00ednea como uma das 500 pessoas mais influentes da Am\u00e9rica Latina.&nbsp;<\/p>\n\n\n\n<p>Al\u00e9m disso, foi a primeira pessoa com defici\u00eancia a conquistar o t\u00edtulo de Top Voice do LinkedIn, destacando-se pelo conte\u00fado relevante que promove discuss\u00f5es sobre acessibilidade e inclus\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quais temas Andrea Schwarz aborda em suas palestras?<\/h2>\n\n\n\n<p>As palestras de Andrea s\u00e3o conhecidas por abordar temas que ressoam tanto com empresas quanto com o p\u00fablico. Assim, ela:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>compartilha sua jornada pessoal para inspirar outros;<\/li>\n\n\n\n<li>explica como criar ambientes de trabalho mais inclusivos;<\/li>\n\n\n\n<li>enfatiza a import\u00e2ncia das mulheres ocuparem espa\u00e7os de destaque;<\/li>\n\n\n\n<li>ensina lideran\u00e7as a serem mais inclusivas;<\/li>\n\n\n\n<li>discute a import\u00e2ncia de tornar ambientes e tecnologias mais acess\u00edveis.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Empoderamento feminino e lideran\u00e7a<\/h3>\n\n\n\n<p>Andrea destaca o papel crucial que as mulheres desempenham na promo\u00e7\u00e3o da inclus\u00e3o e como elas podem ser agentes de mudan\u00e7a dentro de suas organiza\u00e7\u00f5es.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 o impacto das palestras de Andrea Schwarz?<\/h2>\n\n\n\n<p>As palestras de Andrea Schwarz n\u00e3o apenas informam, mas tamb\u00e9m transformam mentalidades. Ela leva o p\u00fablico a uma reflex\u00e3o profunda sobre a import\u00e2ncia de criar espa\u00e7os mais justos e acess\u00edveis.&nbsp;<\/p>\n\n\n\n<p>Por meio de seus relatos, ent\u00e3o, ela sensibiliza e inspira empresas a tomarem a\u00e7\u00f5es concretas que promovam a inclus\u00e3o real.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sensibiliza\u00e7\u00e3o e conscientiza\u00e7\u00e3o em a\u00e7\u00e3o<\/h3>\n\n\n\n<p>Andrea utiliza sua experi\u00eancia para exemplificar o poder que pequenas a\u00e7\u00f5es podem ter. Ela ressalta como mudan\u00e7as simples, como, por exemplo, as melhorias de acessibilidade, podem transformar a vida de quem tem defici\u00eancia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 o novo livro de Andrea Schwarz?<\/h2>\n\n\n\n<p>Andrea Schwarz est\u00e1 prestes a lan\u00e7ar seu mais novo livro, intitulado &#8220;Eu parei de andar e aprendi a voar: Como transformei desafios em asas&#8221;.&nbsp;<\/p>\n\n\n\n<p>A obra, que ser\u00e1 lan\u00e7ada no dia 27 de novembro de 2024, promete ser um relato emocionante e inspirador sobre sua trajet\u00f3ria de:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>supera\u00e7\u00e3o;<\/li>\n\n\n\n<li>resili\u00eancia;<\/li>\n\n\n\n<li>transforma\u00e7\u00e3o pessoal.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">O que motivou Andrea Schwarz a escrever &#8220;Eu Parei de Andar e Aprendi a Voar\u201d?<\/h2>\n\n\n\n<p>Aos 22 anos, Andrea passou por um evento que mudou completamente o curso de sua vida: tornou-se cadeirante devido a uma condi\u00e7\u00e3o cong\u00eanita na medula.&nbsp;<\/p>\n\n\n\n<p>Esse momento, que poderia ter representado o fim de muitos sonhos, serviu como um ponto de virada para Andrea.&nbsp;<\/p>\n\n\n\n<p>No livro, ali\u00e1s, ela compartilha como enfrentou o <a href=\"https:\/\/iigual.com.br\/blog\/o-que-e-capacitismo\/\" target=\"_blank\" rel=\"noreferrer noopener\">capacitismo<\/a> e a descren\u00e7a que muitos tinham em sua capacidade de ter uma vida plena e produtiva.\u00a0<\/p>\n\n\n\n<p>A obra \u00e9 uma verdadeira aula sobre como transformar desafios em oportunidades e seguir em frente com for\u00e7a e prop\u00f3sito.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2024\/11\/eu-parei-de-andar-e-aprendi-a-voar-1024x683.webp\" alt=\"Duas fotos de Andrea Schwarz segurando seu livro &quot;Eu Parei de Andar e Aprendi a Voar&quot;, sorrindo em uma delas e escondendo parcialmente o rosto com o livro na outra.\" class=\"wp-image-5321\" srcset=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2024\/11\/eu-parei-de-andar-e-aprendi-a-voar-1024x683.webp 1024w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2024\/11\/eu-parei-de-andar-e-aprendi-a-voar-300x200.webp 300w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2024\/11\/eu-parei-de-andar-e-aprendi-a-voar-768x512.webp 768w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2024\/11\/eu-parei-de-andar-e-aprendi-a-voar-750x500.webp 750w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2024\/11\/eu-parei-de-andar-e-aprendi-a-voar-1140x760.webp 1140w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2024\/11\/eu-parei-de-andar-e-aprendi-a-voar.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">O lan\u00e7amento de &#8220;Eu parei de andar e aprendi a voar&#8221; acontecer\u00e1 no dia 27 de novembro de 2024<\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Quais s\u00e3o os principais temas abordados em &#8220;Eu Parei de Andar e Aprendi a Voar\u201d?<\/h2>\n\n\n\n<p>O livro aborda de forma \u00edntima e detalhada os seguintes temas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>como Andrea enfrentou o desafio de se adaptar a uma nova realidade e transform\u00e1-la em algo positivo;<\/li>\n\n\n\n<li>o processo de fundar a iigual e o impacto que a empresa tem gerado na inclus\u00e3o de pessoas com defici\u00eancia no mercado de trabalho;<\/li>\n\n\n\n<li>a trajet\u00f3ria de Andrea como mulher, m\u00e3e e empres\u00e1ria que desafia estigmas e quebra <a href=\"https:\/\/iigual.com.br\/blog\/barreiras-sinonimo\/\" target=\"_blank\" rel=\"noreferrer noopener\">barreiras<\/a>;<\/li>\n\n\n\n<li>o papel da sociedade e das empresas em promover ambientes acess\u00edveis e inclusivos, com insights sobre a import\u00e2ncia de pol\u00edticas que favore\u00e7am a equidade.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Onde e quando ser\u00e1 o lan\u00e7amento do livro &#8220;Eu Parei de Andar e Aprendi a Voar\u201d?<\/h2>\n\n\n\n<p>O lan\u00e7amento de &#8220;Eu parei de andar e aprendi a voar&#8221; acontecer\u00e1 no dia 27 de novembro de 2024, na <a href=\"https:\/\/www.travessa.com.br\/wpgEventoTravessa.aspx?evento=ed97a3f2-4922-48e9-ae86-e621766f9783&amp;srsltid=AfmBOopSdBPDPbDj9LPHe1IE-SbOMBtVXDaUOWiyFmY_WqK6D7mUISna\" target=\"_blank\" rel=\"noreferrer noopener\">Livraria Travessa<\/a> \u2013 Shopping Villa Lobos, em S\u00e3o Paulo, SP.\u00a0<\/p>\n\n\n\n<p>O evento, ent\u00e3o, est\u00e1 programado para come\u00e7ar \u00e0s 19:00, e contar\u00e1 com a presen\u00e7a da autora para uma sess\u00e3o de aut\u00f3grafos e bate-papo com os leitores.&nbsp;<\/p>\n\n\n\n<p>Este ser\u00e1 um momento especial para os f\u00e3s e admiradores da trajet\u00f3ria de Andrea Schwarz, que ter\u00e3o a chance de conhecer mais de perto a mulher por tr\u00e1s da hist\u00f3ria.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Por que o livro \u00e9 uma leitura essencial?<\/h2>\n\n\n\n<p>O livro \u00e9 uma fonte de inspira\u00e7\u00e3o para qualquer pessoa que j\u00e1 enfrentou desafios ou busca for\u00e7as para super\u00e1-los.&nbsp;<\/p>\n\n\n\n<p>Assim, Andrea usa sua pr\u00f3pria hist\u00f3ria como um exemplo de que \u00e9 poss\u00edvel transformar situa\u00e7\u00f5es dif\u00edceis em impulso para al\u00e7ar voos maiores.&nbsp;<\/p>\n\n\n\n<p>Al\u00e9m disso, a obra traz reflex\u00f5es importantes sobre inclus\u00e3o, resili\u00eancia e a capacidade de encontrar prop\u00f3sito em meio \u00e0s adversidades.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Li\u00e7\u00f5es valiosas para todos<\/h3>\n\n\n\n<p>Andrea destaca que o aprendizado mais importante que deseja compartilhar \u00e9 que limita\u00e7\u00f5es n\u00e3o definem o potencial de ningu\u00e9m.&nbsp;<\/p>\n\n\n\n<p>Ela nos lembra que \u00e9 poss\u00edvel adaptar, inovar e se reinventar em qualquer circunst\u00e2ncia, sempre buscando impactar positivamente a vida das pessoas ao redor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como adquirir &#8220;Eu Parei de Andar e Aprendi a Voar\u201d?<\/h2>\n\n\n\n<p>O livro estar\u00e1 dispon\u00edvel para compra tanto no evento de lan\u00e7amento quanto nas principais livrarias f\u00edsicas e digitais do Brasil. Al\u00e9m disso, a obra poder\u00e1 ser adquirida diretamente pelo site da editora FinAppLab e em plataformas online como Amazon, Submarino e outras.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que mais saber sobre &#8220;Eu Parei de Andar e Aprendi a Voar\u201d?<\/h2>\n\n\n\n<p>Veja, ent\u00e3o, as perguntas mais comuns sobre o tema.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Como a experi\u00eancia de Andrea pode inspirar pessoas que enfrentam dificuldades na vida?<\/h3>\n\n\n\n<p>Andrea oferece um exemplo poderoso de como aceitar e superar desafios. Assim, a sua trajet\u00f3ria mostra que, mesmo nas circunst\u00e2ncias mais dif\u00edceis, \u00e9 poss\u00edvel redescobrir a alegria, encontrar prop\u00f3sito e construir uma nova perspectiva sobre a vida.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Que papel a mentalidade positiva desempenha no processo de adapta\u00e7\u00e3o, segundo Andrea Schwarz?<\/h3>\n\n\n\n<p>No livro, Andrea destaca que uma mentalidade positiva \u00e9 crucial para a adapta\u00e7\u00e3o. Enfrentar a vida com otimismo e esperan\u00e7a, de fato, permite encontrar solu\u00e7\u00f5es e novas possibilidades, transformando o que parece ser um obst\u00e1culo em uma oportunidade.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">&#8220;Eu parei de Andar e Aprendi a Voar&#8221; aborda o tema da autossupera\u00e7\u00e3o?<\/h3>\n\n\n\n<p>O livro \u00e9 uma verdadeira li\u00e7\u00e3o de autossupera\u00e7\u00e3o. Isso porque, Andrea compartilha como, ao longo de sua jornada, foi aprendendo a quebrar barreiras e superar suas pr\u00f3prias limita\u00e7\u00f5es, provando que a for\u00e7a interior \u00e9 um fator essencial para enfrentar adversidades.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Qual mensagem Andrea Schwarz deseja passar com o t\u00edtulo &#8220;Eu Parei de Andar e Aprendi a Voar&#8221;?<\/h3>\n\n\n\n<p>O t\u00edtulo sugere que, mesmo com a perda de uma habilidade f\u00edsica, Andrea encontrou uma forma de &#8220;voar&#8221; mental e emocionalmente. A mensagem \u00e9 de que, ao aceitar e transformar suas dificuldades, ela conseguiu alcan\u00e7ar uma liberdade interior e uma nova forma de viver.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em sua biografia &#8220;Eu Parei de Andar e Aprendi a Voar&#8220;, Andrea Schwarz, um exemplo vivo de como transformar adversidades em asas para voar mais alto, revela sua jornada de desafios e descobertas ap\u00f3s tornar-se cadeirante aos 22 anos.\u00a0 Esta obra inspiradora explora os temas de supera\u00e7\u00e3o, bem como, aceita\u00e7\u00e3o, inclus\u00e3o, prop\u00f3sito e empreendedorismo, refletindo [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":5320,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inclusao"],"_links":{"self":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts\/5319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/comments?post=5319"}],"version-history":[{"count":1,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts\/5319\/revisions"}],"predecessor-version":[{"id":5322,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts\/5319\/revisions\/5322"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/media\/5320"}],"wp:attachment":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/media?parent=5319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/categories?post=5319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/tags?post=5319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}