{"id":4131,"date":"2024-01-16T08:00:00","date_gmt":"2024-01-16T11:00:00","guid":{"rendered":"https:\/\/iigual.com.br\/blog\/?p=4131"},"modified":"2024-01-17T12:04:55","modified_gmt":"2024-01-17T15:04:55","slug":"adaptar-sinonimo","status":"publish","type":"post","link":"https:\/\/iigual.com.br\/blog\/adaptar-sinonimo\/","title":{"rendered":"5 maneiras de adaptar sua empresa ao contratar pessoas com defici\u00eancia"},"content":{"rendered":"\n<p>As empresas t\u00eam que se <strong>adaptar<\/strong> para dar aos profissionais com defici\u00eancia a chance de se destacarem em suas \u00e1reas de trabalho. Isso porque, \u00e9 a melhor forma de gerar uma boa inclus\u00e3o no mercado, o que garante dignidade e equidade a todos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Por que adaptar a sua empresa para pessoas com defici\u00eancia?<\/h2>\n\n\n\n<p>As empresas t\u00eam que se <strong>adaptar<\/strong> para promover sua cidadania, diversificar o seu quadro e garantir que sua vis\u00e3o de neg\u00f3cios seja inclusiva. Dessa forma, al\u00e9m de garantir os direitos e cumprir as leis, esse \u00e9 um modo de agregar muito a sua equipe.<\/p>\n\n\n\n<p>Hoje, mesmo com avan\u00e7os ao contratar as pessoas com defici\u00eancia e com a <a href=\"https:\/\/www.gov.br\/trabalho-e-emprego\/pt-br\/noticias-e-conteudo\/2023\/julho\/lei-de-cotas-para-pessoas-com-deficiencia-completa-32-anos-nesta-segunda-feira-24\" target=\"_blank\" rel=\"noreferrer noopener\">lei de cotas<\/a>, os locais precisam ser acess\u00edveis. Assim, isso garante que se tenha conforto e todos os recursos para que todos deem o seu melhor.<\/p>\n\n\n\n<p>A empresa deve mudar seu espa\u00e7o para que os limites f\u00edsicos n\u00e3o impe\u00e7a ningu\u00e9m de exercer suas tarefas. Por isso, vale a pena conhecer algumas formas de adequar o seu local.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2024\/01\/adaptar-1.jpg\" alt=\"5 maneiras de adaptar sua empresa ao contratar pessoas com defici\u00eancia\" class=\"wp-image-4134\" srcset=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2024\/01\/adaptar-1.jpg 1200w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2024\/01\/adaptar-1-300x200.jpg 300w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2024\/01\/adaptar-1-1024x683.jpg 1024w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2024\/01\/adaptar-1-768x512.jpg 768w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2024\/01\/adaptar-1-750x500.jpg 750w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2024\/01\/adaptar-1-1140x760.jpg 1140w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">Saber como adaptar a sua empresa para contratar pessoas com defici\u00eancia \u00e9 essencial. Imagem de Thirdman em Pexels.<\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Como adaptar o local ao contratar pessoas com defici\u00eancia?<\/h2>\n\n\n\n<p>Na hora de <strong>adaptar<\/strong> sua empresa para contratar pessoas com defici\u00eancia \u00e9 crucial pensar em tudo que possa ajudar todos a ficarem a vontade. Portanto, a seguir est\u00e3o algumas dicas cruciais que te auxiliam nesse processo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1 &#8211; Promova a inclus\u00e3o<\/h3>\n\n\n\n<p>O primeiro passo para que todos se sintam a vontade \u00e9 estimular que os membros se aceitem. Ent\u00e3o, isso pode surgir ao promover atividades e elaborar um programa de inclus\u00e3o, onde haja valores e regras bem claras sobre:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>n\u00e3o rotular;<\/li>\n\n\n\n<li>flexibilizar o perfil;<\/li>\n\n\n\n<li>n\u00e3o generalizar.<\/li>\n<\/ul>\n\n\n\n<p>\u00c9 interessante estimular a aceita\u00e7\u00e3o de membros, com a promo\u00e7\u00e3o de atividades onde todos interajam entre si e possam compartilhar suas vis\u00f5es de mundo. Por isso, \u00e9 importante que o Recursos Humanos tenha um plano claro de inclus\u00e3o antes de divulgar a vaga.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Cultura de respeito<\/h4>\n\n\n\n<p>Um dos grandes pontos para se <strong>adaptar<\/strong> \u00e9 difundir uma cultura de respeito \u00e0s diferen\u00e7as. Dessa forma, a sensa\u00e7\u00e3o de equidade deve chegar a todos, mesmo nos setores mais altos.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Trate todo do mesmo jeito<\/h4>\n\n\n\n<p>\u00c9 crucial que a empresa trate todos da mesma forma, desde as responsabilidades at\u00e9 as cobran\u00e7as. Assim, tenha o mesmo regime de regras e san\u00e7\u00f5es, para que todos se sintam iguais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2 &#8211; Promova acessibilidade<\/h3>\n\n\n\n<p>A acessibilidade \u00e9 um ponto essencial para que a pessoa com defici\u00eancia possa executar sua fun\u00e7\u00e3o. Ent\u00e3o, crie um <a href=\"https:\/\/iigual.com.br\/blog\/plano-de-carreira-pcd\/\" target=\"_blank\" rel=\"noreferrer noopener\">plano de carreira<\/a> para ela e fa\u00e7a as mudan\u00e7as necess\u00e1rias no espa\u00e7o f\u00edsico.<\/p>\n\n\n\n<p>Uma boa forma de conseguir isso \u00e9 gerar um mapa das fun\u00e7\u00f5es ou cargos que potencializam as suas capacidades. Al\u00e9m disso, promova a\u00e7\u00f5es de acesso, elimine as barreiras f\u00edsicas e de comunica\u00e7\u00e3o e ou\u00e7a seus funcion\u00e1rios para entender como se <strong>adaptar<\/strong>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Garanta a ergonomia&nbsp;<\/h4>\n\n\n\n<p>A ergonomia \u00e9 muito importante para que as pessoas com defici\u00eancia cumpram suas tarefas. Por isso, foque em evitar que a produtividade afete o seu trabalho ou traga algum tipo de riscos \u00e0 sa\u00fade.<\/p>\n\n\n\n<p>\u00c9 crucial ter uma empresa com sinaliza\u00e7\u00e3o t\u00e1tica, visual, sonora e acesso sem barreiras. Portanto, \u00e9 vital ter banheiros adaptados para cada um, bem como, rampas de acessibilidade, afinal, a liberdade e a autonomia deve vir em primeiro lugar.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Fa\u00e7a as mudan\u00e7as necess\u00e1rias&nbsp;<\/h4>\n\n\n\n<p><strong>Adaptar<\/strong> o ambiente f\u00edsico deve ser um dos principais crit\u00e9rios e isso \u00e9 poss\u00edvel ao elaborar um mapa de acessibilidade. Assim, ele deve identificar barreiras e limita\u00e7\u00f5es ao se locomover, de acordo com a NBR-9050.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2024\/01\/adaptar-2.jpg\" alt=\"5 maneiras de adaptar sua empresa ao contratar pessoas com defici\u00eancia\" class=\"wp-image-4135\" srcset=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2024\/01\/adaptar-2.jpg 1200w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2024\/01\/adaptar-2-300x200.jpg 300w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2024\/01\/adaptar-2-1024x683.jpg 1024w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2024\/01\/adaptar-2-768x512.jpg 768w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2024\/01\/adaptar-2-750x500.jpg 750w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2024\/01\/adaptar-2-1140x760.jpg 1140w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">Aprenda a adaptar a sua empresa para contratar pessoas com defici\u00eancia. Imagem de Mikhail Nilov em Pexels.<\/figcaption><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\">3 &#8211; Promova treinos<\/h3>\n\n\n\n<p>\u00c9 crucial promover treinos em todos os setores para ter uma toler\u00e2ncia maior dentro de seu grupo. Ent\u00e3o, treine a sua equipe e promova cursos para capacitar sobre como abordar pessoas com defici\u00eancia. Por isso, \u00e9 bom ir al\u00e9m, a fim de evitar o <a href=\"https:\/\/iigual.com.br\/blog\/capacitismo\/\" target=\"_blank\" rel=\"noreferrer noopener\">capacitismo<\/a>.<\/p>\n\n\n\n<p>Treine todos para identificar as habilidades para propiciar uma inclus\u00e3o mais justa. Dessa forma, promova palestras com os gestores e a equipe, al\u00e9m de outras atividades com todos os colaboradores para criar um ambiente mais inclusivo.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Promova toler\u00e2ncia em todos os setores<\/h4>\n\n\n\n<p>\u00c9 importante que o clima da empresa seja favor\u00e1vel a toler\u00e2ncia e respeito, n\u00e3o s\u00f3 para as pessoas com defici\u00eancia, mas para todas as minorias. Por isso, \u00e9 bom <strong>adaptar<\/strong> a sua linguagem para que os l\u00edderes saibam o melhor modo de abordar para ter bons resultados.<\/p>\n\n\n\n<p>Atingir esse n\u00edvel \u00e9 algo que s\u00f3 se consegue a partir de um treino intenso, onde os funcion\u00e1rios sintam que n\u00e3o existe distin\u00e7\u00e3o. Assim, aborde temas como preconceito e naturalize a diferen\u00e7a entre as pessoas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4 &#8211; Crie descri\u00e7\u00f5es de cargos claras<\/h3>\n\n\n\n<p>A lista de requisitos em linguagem simples e aberta aumenta suas chances de contratar uma for\u00e7a de trabalho diversa, como com pessoas com defici\u00eancia. Ent\u00e3o, deixe claro qual \u00e9 a vaga e as atribui\u00e7\u00f5es que ela precisa para que todos cumpram as suas tarefas.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Crie um plano de carreira<\/h4>\n\n\n\n<p>Para <strong>adaptar<\/strong> a empresa e diminuir a taxa de rotatividade desses profissionais, \u00e9 crucial elaborar um plano de carreira. Dessa forma, tenha um time com empatia para tra\u00e7ar um futuro profissional para os seus novos contratados.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">5 &#8211; Acompanhe de perto o desenvolvimento do profissional\u00a0<\/h3>\n\n\n\n<p>Outra maneira de aproximar a sua marca das pessoas com defici\u00eancia \u00e9 acompanhar de perto como elas desenvolvem o seu trabalho. Portanto, \u00e9 mais f\u00e1cil entender o que precisam e como o neg\u00f3cio pode atuar para que isso funcione.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quais s\u00e3o benef\u00edcios de se adaptar as pessoas com defici\u00eancia?<\/h2>\n\n\n\n<p><strong>Adaptar <\/strong>a empresa para atender estes profissionais traz benef\u00edcios \u00fanicos, como atrair uma qualifica\u00e7\u00e3o maior. Al\u00e9m disso, melhora a reputa\u00e7\u00e3o e a imagem, o que estimula a coopera\u00e7\u00e3o entre os membros de uma equipe e promove um aumento da produtividade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As empresas t\u00eam que se adaptar para dar aos profissionais com defici\u00eancia a chance de se destacarem em suas \u00e1reas de trabalho. Isso porque, \u00e9 a melhor forma de gerar uma boa inclus\u00e3o no mercado, o que garante dignidade e equidade a todos. Por que adaptar a sua empresa para pessoas com defici\u00eancia? As empresas [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":4132,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[241,1231,87,101],"class_list":["post-4131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inclusao","tag-acessibilidade","tag-adaptar","tag-empresa","tag-pessoas-com-deficiencia"],"_links":{"self":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts\/4131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/comments?post=4131"}],"version-history":[{"count":2,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts\/4131\/revisions"}],"predecessor-version":[{"id":4136,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts\/4131\/revisions\/4136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/media\/4132"}],"wp:attachment":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/media?parent=4131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/categories?post=4131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/tags?post=4131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}