{"id":2767,"date":"2023-02-22T11:00:00","date_gmt":"2023-02-22T14:00:00","guid":{"rendered":"https:\/\/iigual.com.br\/blog\/?p=2767"},"modified":"2023-02-08T04:31:45","modified_gmt":"2023-02-08T07:31:45","slug":"falta-de-informacao","status":"publish","type":"post","link":"https:\/\/iigual.com.br\/blog\/falta-de-informacao\/","title":{"rendered":"Como combater a falta de informa\u00e7\u00e3o dentro das empresas com rela\u00e7\u00e3o a diversidade e inclus\u00e3o?"},"content":{"rendered":"\n<p>A <strong>falta de informa\u00e7\u00e3o<\/strong> ainda \u00e9 um problema ainda mais quando se busca promover a diversidade e inclus\u00e3o no ambiente de trabalho. Por isso, a <a href=\"https:\/\/iigual.com.br\/blog\/2023\/01\/16\/educacao-nas-empresas\/\" target=\"_blank\" rel=\"noreferrer noopener\">educa\u00e7\u00e3o nas empresas<\/a> \u00e9 um fator essencial para eliminar essas falsas ideias e conscientizar a todos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A falta de informa\u00e7\u00e3o \u00e9 um entrave para promover a diversidade e inclus\u00e3o?<\/h2>\n\n\n\n<p>De acordo com um levantamento do Vagas.com sobre <a href=\"https:\/\/www3.ethos.org.br\/wp-content\/uploads\/2018\/06\/VAGAS-Diversidade-20.06.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">diversidade<\/a> no trabalho, a <strong>falta de informa\u00e7\u00e3o<\/strong> \u00e9 um dos fatores principais para a aus\u00eancia de pol\u00edticas de inclus\u00e3o. Essa foi a resposta de 48% dos entrevistados, enquanto os demais apontados foram:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>aceita\u00e7\u00e3o e respeito dos gestores, com 25%;<\/li>\n\n\n\n<li>posicionamento dos colegas de trabalho (14%);<\/li>\n\n\n\n<li>falta de preparo do setor de RH com 9%;<\/li>\n\n\n\n<li>por fim, a discrimina\u00e7\u00e3o com 4%.<\/li>\n<\/ul>\n\n\n\n<p>Nesse cen\u00e1rio, fazer com que as pessoas conhe\u00e7am mais sobre o assunto e se livrem de ideias equivocadas, baseadas no senso comum, \u00e9 essencial. Somente dessa forma \u00e9 poss\u00edvel dar equidade de oportunidades a todos, independente de suas condi\u00e7\u00f5es.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/02\/Falta-de-informacao-1.jpg\" alt=\"Plateia de colaboradores em evento sobre Falta de informa\u00e7\u00e3o\" class=\"wp-image-2771\" title=\"Plateia: Falta de informa\u00e7\u00e3o\" srcset=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/02\/Falta-de-informacao-1.jpg 1200w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/02\/Falta-de-informacao-1-300x200.jpg 300w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/02\/Falta-de-informacao-1-1024x683.jpg 1024w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/02\/Falta-de-informacao-1-768x512.jpg 768w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/02\/Falta-de-informacao-1-750x500.jpg 750w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/02\/Falta-de-informacao-1-1140x760.jpg 1140w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">A falta de informa\u00e7\u00e3o \u00e9 um dos principais fatores que impede uma pol\u00edtica de inclus\u00e3o eficaz nas empresas. Imagem de Matheus Bertelli no Pexels<\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Quais os preju\u00edzos da falta de informa\u00e7\u00e3o no ambiente de trabalho?<\/h2>\n\n\n\n<p>Um dos principais preju\u00edzos da <strong>falta de informa\u00e7\u00e3o<\/strong> \u00e9 a limita\u00e7\u00e3o das oportunidades de inclus\u00e3o dentro de uma empresa.&nbsp;<\/p>\n\n\n\n<p>Isso ocorre porque muitas vezes, o pr\u00f3prio setor de Recursos Humanos n\u00e3o sabe como conduzir um bom <a href=\"https:\/\/iigual.com.br\/blog\/2022\/12\/15\/processo-seletivo\/\" target=\"_blank\" rel=\"noreferrer noopener\">processo seletivo<\/a> para contratar pessoas com defici\u00eancia, por exemplo.<\/p>\n\n\n\n<p>Com isso, em muitos casos uma empresa contrata essas pessoas apenas para cumprir com a Lei de Cotas, mas sem aproveitar as suas compet\u00eancias da melhor forma. Ou seja, \u00e9 ruim para o neg\u00f3cio e tamb\u00e9m para quem ocupa a vaga, que n\u00e3o se sente integrado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Uso de termos pejorativos<\/h3>\n\n\n\n<p>Outro reflexo da desinforma\u00e7\u00e3o \u00e9 o uso de termos que tem um cunho depreciativo ao tratar com pessoas com defici\u00eancia. Nesse sentido, algumas das express\u00f5es incorretas, mas que ainda se ouvem por falta de conhecimento s\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>excepcional;<\/li>\n\n\n\n<li>pessoa portadora de necessidades especiais;<\/li>\n\n\n\n<li>surdo-mudo;<\/li>\n\n\n\n<li>pessoa normal, ao se referir \u00e0quelas que n\u00e3o t\u00eam defici\u00eancia.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Quais as a\u00e7\u00f5es para combater a falta de informa\u00e7\u00e3o?<\/h2>\n\n\n\n<p>Para combater a <strong>falta de informa\u00e7\u00e3o <\/strong>nas empresas \u00e9 essencial investir em a\u00e7\u00f5es de conscientiza\u00e7\u00e3o, que podem ser realizadas em diversos formatos, tais como:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>palestras;<\/li>\n\n\n\n<li>campanhas internas;<\/li>\n\n\n\n<li>treinamentos.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Palestras<\/h3>\n\n\n\n<p>As palestras s\u00e3o uma boa forma de levar informa\u00e7\u00e3o aos funcion\u00e1rios e permite reunir um bom n\u00famero de pessoas de cada vez. Assim, a depender do tamanho da empresa, \u00e9 o modo mais pr\u00e1tico de trabalhar temas como a diversidade e inclus\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Para que isso seja eficaz, o ideal \u00e9 preparar de forma pr\u00e9via o tema, e fazer um planejamento dos pontos que ser\u00e3o tratados. Al\u00e9m disso, \u00e9 bom avisar com anteced\u00eancia sobre o evento, para que todos se programem para reservar esse tempo.&nbsp;<\/p>\n\n\n\n<p>\u00c9 poss\u00edvel contar com a presen\u00e7a de convidados que tenham conhecimento sobre o assunto, o que agrega ainda mais ao conte\u00fado. Nesse caso, \u00e9 preciso buscar algu\u00e9m dentro do perfil e organizar bem de acordo com a agenda dispon\u00edvel.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Campanhas internas<\/h3>\n\n\n\n<p>Outro m\u00e9todo para acabar com a<strong> falta de informa\u00e7\u00e3o<\/strong> \u00e9 investir em campanhas internas, o que pode ser uma alternativa mais em conta. Dessa forma, podem ser utilizados informativos por e-mail, cartazes e banners com orienta\u00e7\u00f5es \u00fateis aos colaboradores.&nbsp;<\/p>\n\n\n\n<p>Tamb\u00e9m \u00e9 poss\u00edvel tratar desses temas durante a SIPAT &#8211; Semana Interna de Preven\u00e7\u00e3o de Acidentes de Trabalho, que ocorre todos os anos nas empresas. Al\u00e9m de falar sobre seguran\u00e7a, esse evento tamb\u00e9m permite incluir assuntos do dia a dia.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"801\" src=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/02\/Falta-de-informacao-2.jpg\" alt=\"Palestra sobre Falta de informa\u00e7\u00e3o em empresa\" class=\"wp-image-2772\" title=\"Empresa: Falta de informa\u00e7\u00e3o\" srcset=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/02\/Falta-de-informacao-2.jpg 1200w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/02\/Falta-de-informacao-2-300x200.jpg 300w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/02\/Falta-de-informacao-2-1024x684.jpg 1024w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/02\/Falta-de-informacao-2-768x513.jpg 768w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/02\/Falta-de-informacao-2-750x501.jpg 750w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/02\/Falta-de-informacao-2-1140x761.jpg 1140w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">Palestras e eventos internos ajudam a combater a falta de informa\u00e7\u00e3o nas empresas. Imagem de Pavel Danilyuk no Pexels<\/figcaption><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\">Treinamentos<\/h3>\n\n\n\n<p>A <a href=\"https:\/\/iigual.com.br\/blog\/2023\/01\/27\/capacitacao-dos-funcionarios\/\" target=\"_blank\" rel=\"noreferrer noopener\">capacita\u00e7\u00e3o dos funcion\u00e1rios<\/a> para lidar com a diversidade no trabalho tamb\u00e9m \u00e9 uma boa forma de trazer mais conhecimento. Assim, podem ser realizados treinamentos espec\u00edficos para essa finalidade, sendo alguns dos temas sugeridos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>como conduzir um processo seletivo para pessoas com defici\u00eancia;<\/li>\n\n\n\n<li>formas de dar um feedback construtivo;<\/li>\n\n\n\n<li>como integrar os funcion\u00e1rios na equipe;<\/li>\n\n\n\n<li>desenvolver a empatia, ao se colocar no lugar do outro.<\/li>\n<\/ul>\n\n\n\n<p>Tais a\u00e7\u00f5es ajudam a fazer com que todos na equipe conhe\u00e7am mais sobre a realidade e as dificuldades que as pessoas com defici\u00eancia encontram para se colocar no mercado de trabalho.&nbsp;<\/p>\n\n\n\n<p>Ainda, permitem que se crie uma consci\u00eancia maior da import\u00e2ncia da inclus\u00e3o e de ter uma equipe diversa, em que cada um traga um pouco de suas experi\u00eancias para o trabalho.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"DIVERSIDADE E INCLUS\u00c3O NAS EMPRESAS\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/0RZw9svMcKw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Quais os respons\u00e1veis por conduzir as campanhas para combater a falta de informa\u00e7\u00e3o?<\/h2>\n\n\n\n<p>O setor de Recursos Humanos \u00e9 um dos principais respons\u00e1veis por combater a <strong>falta de informa\u00e7\u00e3o<\/strong> no ambiente de trabalho. Afinal, ele cuida do capital humano da empresa, e deve conduzir a\u00e7\u00f5es para que se alcance a inclus\u00e3o.<\/p>\n\n\n\n<p>Em contrapartida, \u00e9 necess\u00e1ria tamb\u00e9m a participa\u00e7\u00e3o dos l\u00edderes nesse processo, uma vez que s\u00e3o eles que est\u00e3o em contato direto com as equipes no dia a dia.&nbsp;<\/p>\n\n\n\n<p>Com isso, conseguem identificar primeiro quando h\u00e1 algum problema na integra\u00e7\u00e3o de um funcion\u00e1rio com defici\u00eancia, por exemplo. Assim, pode-se direcionar as campanhas de forma a coibir comportamentos discriminat\u00f3rios em rela\u00e7\u00e3o a esses grupos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Combater a falta de informa\u00e7\u00e3o ajuda na imagem da empresa?<\/h2>\n\n\n\n<p>As a\u00e7\u00f5es contra a <strong>falta de informa\u00e7\u00e3o<\/strong> s\u00e3o capazes de melhorar o clima interno, o que traz uma boa percep\u00e7\u00e3o por parte dos funcion\u00e1rios. Dessa forma, eles se sentem parte de uma organiza\u00e7\u00e3o com responsabilidade social, e que investe na capacita\u00e7\u00e3o.<\/p>\n\n\n\n<p>Isso tem um reflexo positivo no mercado, uma vez que os pr\u00f3prios colaboradores se tornam promotores e passam a defender aquela marca.&nbsp;<\/p>\n\n\n\n<p>Fora isso, fazer com que as pessoas conhe\u00e7am mais a respeito evita que funcion\u00e1rios da propaguem ideias e conceitos equivocados que possam ser associados \u00e0 imagem da empresa.&nbsp;<\/p>\n\n\n\n<p>N\u00e3o raramente ocorrem casos em que uma pessoa exp\u00f5e uma fala preconceituosa nas redes sociais, e ao se descobrir que trabalha em determinada institui\u00e7\u00e3o, \u00e9 preciso fazer uma gest\u00e3o de crise.&nbsp;<\/p>\n\n\n\n<p>Nesse contexto, as a\u00e7\u00f5es pr\u00e9vias de conscientiza\u00e7\u00e3o podem evitar esse tipo de ocorr\u00eancia e ainda refletir de forma positiva na sociedade, porque esses aprendizados ser\u00e3o levados para o dia a dia de cada um.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A falta de informa\u00e7\u00e3o ainda \u00e9 um problema ainda mais quando se busca promover a diversidade e inclus\u00e3o no ambiente de trabalho. Por isso, a educa\u00e7\u00e3o nas empresas \u00e9 um fator essencial para eliminar essas falsas ideias e conscientizar a todos. A falta de informa\u00e7\u00e3o \u00e9 um entrave para promover a diversidade e inclus\u00e3o? De [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2768,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,4,6],"tags":[424,844,845,846,88],"class_list":["post-2767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreira","category-inclusao","category-rh-inclusivo","tag-conscientizacao","tag-desinformacao","tag-expressoes-incorretas","tag-falta-de-informacao","tag-inclusao"],"_links":{"self":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts\/2767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/comments?post=2767"}],"version-history":[{"count":1,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts\/2767\/revisions"}],"predecessor-version":[{"id":2773,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts\/2767\/revisions\/2773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/media\/2768"}],"wp:attachment":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}