{"id":2632,"date":"2023-01-26T11:00:00","date_gmt":"2023-01-26T14:00:00","guid":{"rendered":"https:\/\/iigual.com.br\/blog\/?p=2632"},"modified":"2023-01-05T23:34:32","modified_gmt":"2023-01-06T02:34:32","slug":"selecao-diversa","status":"publish","type":"post","link":"https:\/\/iigual.com.br\/blog\/selecao-diversa\/","title":{"rendered":"Como fazer uma sele\u00e7\u00e3o diversa e inclusiva em sua empresa?"},"content":{"rendered":"\n<p>A <strong>sele\u00e7\u00e3o diversa<\/strong> \u00e9 o processo ideal para atrair novos talentos e se destacar no mercado. Portanto, \u00e9 o caminho que muitas empresas j\u00e1 est\u00e3o trilhando em seus recrutamentos. Ent\u00e3o, se quer ter uma firma mais inclusiva e plural, veja como aplicar essa iniciativa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Uma sele\u00e7\u00e3o diversa inclui quais grupos de minorias?<\/h2>\n\n\n\n<p>Antes de entender como fazer um <a href=\"https:\/\/iigual.com.br\/blog\/2022\/08\/19\/recrutamento-inclusivo\/\" target=\"_blank\" rel=\"noreferrer noopener\">recrutamento inclusivo<\/a> e diverso, \u00e9 importante compreender a ideia de diversidade no ambiente de trabalho. Isso porque, muitos associam este conceito a:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>pessoas negras;<\/li>\n\n\n\n<li>LGBTQIA+.<\/li>\n<\/ul>\n\n\n\n<p>S\u00f3 que vai muito al\u00e9m desses grupos de minorias. Por exemplo, ter mulheres em altos cargos de ger\u00eancia e lideran\u00e7a tamb\u00e9m tem a ver com a diversidade. Bem como, recrutar pessoas com defici\u00eancia, de diferentes religi\u00f5es, idades e etnias.<\/p>\n\n\n\n<p>O estudo da <a href=\"https:\/\/www.mckinsey.com\/featured-insights\/employment-and-growth\/how-advancing-womens-equality-can-add-12-trillion-to-global-growth\" target=\"_blank\" rel=\"noreferrer noopener\">McKinsey &amp; Company<\/a> de 2015 revelou que a igualdade de g\u00eanero pode gerar at\u00e9 2025, o total de 12 trilh\u00f5es de d\u00f3lares ao PIB mundial. Para aqueles que desejam inovar e expandir os neg\u00f3cios, \u00e9 preciso colocar em pr\u00e1tica algumas a\u00e7\u00f5es.<\/p>\n\n\n\n<p>Uma delas \u00e9 criar e aplicar nas empresas um tipo de<strong> sele\u00e7\u00e3o diversa<\/strong> e inclusiva para novos talentos. A fim de desenvolver um local de trabalho mais plural e um recrutamento com menos <a href=\"https:\/\/www.qulture.rocks\/blog\/vieses-inconscientes\" target=\"_blank\" rel=\"noreferrer noopener\">vieses inconscientes<\/a>.\u00a0<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Selecao-diversa-1.jpg\" alt=\"Homem cadeirante em local de trabalho sentado diante de duas colegas apoiados em mesa retangular de madeira\" class=\"wp-image-2635\" title=\"Local de trabalho: sele\u00e7\u00e3o diversa\" srcset=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Selecao-diversa-1.jpg 1200w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Selecao-diversa-1-300x200.jpg 300w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Selecao-diversa-1-1024x683.jpg 1024w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Selecao-diversa-1-768x512.jpg 768w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Selecao-diversa-1-750x500.jpg 750w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Selecao-diversa-1-1140x760.jpg 1140w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">\u00c9 importante mudar o processo de recrutamento do seu RH para uma sele\u00e7\u00e3o diversa e inclusiva. Imagem de freepik no Freepik<\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Como fazer uma sele\u00e7\u00e3o diversa nas empresas?<\/h2>\n\n\n\n<p>Mudar o seu processo de recrutamento e sele\u00e7\u00e3o para deix\u00e1-lo mais inclusivo e diverso est\u00e1 ao seu alcance. Ent\u00e3o, para quem deseja atrair novos talentos para ter uma equipe mais plural, confira as dicas a seguir.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Exig\u00eancia de idioma<\/h3>\n\n\n\n<p>O ingl\u00eas \u00e9 um idioma falado em grande parte do mundo e sem d\u00favida, \u00e9 essencial em diferentes tipos de profiss\u00f5es. No entanto, muitas grandes empresas hoje j\u00e1 deixaram de exigir esse dom\u00ednio em seus candidatos para trainee e est\u00e1gio, por exemplo.<\/p>\n\n\n\n<p>Algumas, inclusive, oferecem um curso de idiomas como benef\u00edcio assim que contrata a pessoa. O que, com certeza, \u00e9 uma \u00f3tima iniciativa.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">95% da popula\u00e7\u00e3o brasileira n\u00e3o domina o ingl\u00eas<\/h4>\n\n\n\n<p>De acordo com um levantamento da British Council, somente 5% dos brasileiros t\u00eam dom\u00ednio sobre a l\u00edngua inglesa. Portanto, as firmas que exigem um n\u00edvel avan\u00e7ado neste idioma, elimina 95% dos seus candidatos, o que prejudica uma <strong>sele\u00e7\u00e3o diversa<\/strong> e inclusiva.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sensibilize o seu RH<\/h3>\n\n\n\n<p>At\u00e9 mesmo o seu setor de Recursos Humanos n\u00e3o \u00e9 livre do vi\u00e9s inconsciente. Isso porque, muitos ainda ficam contratando sempre os mesmos perfis de profissionais. Neste caso, ent\u00e3o, \u00e9 essencial sensibilizar a equipe em rela\u00e7\u00e3o \u00e0s minorias como:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/iigual.com.br\/blog\/2022\/12\/23\/pessoas-com-deficiencia-26\/\" target=\"_blank\" rel=\"noreferrer noopener\">pessoas com defici\u00eancia<\/a>;<\/li>\n\n\n\n<li>ind\u00edgenas;<\/li>\n\n\n\n<li>negros;<\/li>\n\n\n\n<li>mulheres;<\/li>\n\n\n\n<li>LGBTQIA+;<\/li>\n\n\n\n<li>pessoas com mais de 50 anos.<\/li>\n<\/ul>\n\n\n\n<p>\u00c9 importante que conhe\u00e7am as causas desses grupos e estejam abertos a vislumbrar o potencial de cada um, sem olhar as diferen\u00e7as ou limita\u00e7\u00f5es.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Descri\u00e7\u00e3o das vagas<\/h3>\n\n\n\n<p>Uma <strong>sele\u00e7\u00e3o diversa<\/strong> e inclusiva requer um cuidado especial j\u00e1 na parte de descrever a vaga de emprego. Assim, a empresa deve usar termos mais neutros, fora do padr\u00e3o masculino, por exemplo, \u201ccargos para pessoas desenvolvedoras de software\u201d.<\/p>\n\n\n\n<p>Caso o seu RH esteja tendo dificuldade nesse processo, pe\u00e7a a ajuda de outros colaboradores, em especial, eventuais comit\u00eas de diversidade ou grupos que fomentem a inclus\u00e3o social no local de trabalho.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Tenha um servi\u00e7o de consultoria para auxiliar nessa tarefa<\/h4>\n\n\n\n<p>Na aus\u00eancia dessas equipes, vale contratar um servi\u00e7o de consultoria como o da iigual para contribuir em sua <strong>sele\u00e7\u00e3o diversa<\/strong> de talentos plurais. Afinal, a mesma j\u00e1 incluiu mais de 18 mil pessoas com defici\u00eancia no mercado de trabalho em mais de mil empresas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Uma sele\u00e7\u00e3o diversa requer a tecnologia como aliada<\/h3>\n\n\n\n<p>\u00c9 fato que a pandemia de COVID-19 trouxe consigo a transforma\u00e7\u00e3o digital nas firmas. Dessa forma, muitas delas tiveram que se adaptar depressa, inclusive, setores como o de RH.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"A Tecnologia e a Inclus\u00e3o Social\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/DFRJC9FEH2k?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p>Com o trabalho remoto, muitos l\u00edderes optaram por oferecer um <a href=\"https:\/\/iigual.com.br\/blog\/2022\/12\/15\/processo-seletivo\/\" target=\"_blank\" rel=\"noreferrer noopener\">processo seletivo<\/a> em outras regi\u00f5es, muitas delas longe dos grandes centros urbanos. As entrevistas, ent\u00e3o, acontecem de forma online, o que permite a contrata\u00e7\u00e3o de pessoas de qualquer estado.<\/p>\n\n\n\n<p>Esse tipo de <strong>sele\u00e7\u00e3o diversa e virtual<\/strong> tamb\u00e9m \u00e9 uma vantagem para pessoas que t\u00eam dificuldade de locomo\u00e7\u00e3o, seja por alguma defici\u00eancia f\u00edsica ou uma quest\u00e3o de dist\u00e2ncia.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Selecao-diversa-2.jpg\" alt=\"Homem em sala de empresa sentado diante de mesa e na frente de janelas de vidro aperta m\u00e3os de mulher cadeirante de cabelo curto como s\u00edmbolo de acordo ou fechamento de contrato\" class=\"wp-image-2636\" title=\"Acordo: sele\u00e7\u00e3o diversa\" srcset=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Selecao-diversa-2.jpg 1200w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Selecao-diversa-2-300x200.jpg 300w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Selecao-diversa-2-1024x683.jpg 1024w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Selecao-diversa-2-768x512.jpg 768w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Selecao-diversa-2-750x500.jpg 750w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Selecao-diversa-2-1140x760.jpg 1140w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">A sele\u00e7\u00e3o diversa pode ser feita de forma online antes da contrata\u00e7\u00e3o. Imagem de freepik no Freepik<\/figcaption><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\">Exponha as causas da empresa<\/h3>\n\n\n\n<p>\u00c9 importante que o candidato se identifique com a vaga de emprego e com a empresa. Por exemplo, suponha que o seu neg\u00f3cio esteja fazendo um recrutamento exclusivo para pessoas com defici\u00eancia.<\/p>\n\n\n\n<p>A firma deve mostrar todas as a\u00e7\u00f5es que realiza em prol da acessibilidade, bem como, exibir depoimentos dos profissionais que j\u00e1 atuam ali e possuem algum tipo de defici\u00eancia, a fim de comprovar que a corpora\u00e7\u00e3o \u00e9 mesmo plural e inclusiva.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Gere no candidato a sensa\u00e7\u00e3o de pertencimento<\/h4>\n\n\n\n<p>N\u00e3o adianta focar em uma <strong>sele\u00e7\u00e3o diversa<\/strong> e no resto do ano n\u00e3o criar nenhum tipo de a\u00e7\u00e3o interna e externa voltada para a sua equipe plural. Dessa forma, \u00e9 crucial dar import\u00e2ncia a datas como:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>21 de mar\u00e7o: Dia Internacional contra a Discrimina\u00e7\u00e3o Racial;<\/li>\n\n\n\n<li>28 de junho: Dia do Orgulho LGBTQIA+;<\/li>\n\n\n\n<li>3 de dezembro: Dia Internacional da Pessoa com Defici\u00eancia.<\/li>\n<\/ul>\n\n\n\n<p>Isso vai gerar uma forte emo\u00e7\u00e3o de pertencimento ao seu time diverso e ainda, far\u00e1 com que a sua empresa seja bem vista pelo p\u00fablico e o mercado em que atua.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 a import\u00e2ncia de fazer uma sele\u00e7\u00e3o diversa?<\/h2>\n\n\n\n<p>Uma firma que tem funcion\u00e1rios de distintos interesses, idades e culturas, t\u00eam chances maiores de desenvolver solu\u00e7\u00f5es mais inovadoras. Isso porque, pessoas plurais enxergam a mesma quest\u00e3o de diferentes maneiras.<\/p>\n\n\n\n<p>Quando a diversidade se faz presente em uma organiza\u00e7\u00e3o, o p\u00fablico consegue detectar isso de cara e logo, passa a se interessar mais por ela. Afinal, a empresa consegue mostrar na pr\u00e1tica que leva a s\u00e9rio a vontade de ter um mundo mais diverso e inclusivo.<\/p>\n\n\n\n<p>Com a D&amp;I t\u00e3o em pauta nos \u00faltimos tempos, bem como, o conceito de equidade de oportunidades, investir em uma <strong>sele\u00e7\u00e3o diversa<\/strong> se torna cada vez mais urgente para os neg\u00f3cios que desejam se manter relevantes no mercado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A sele\u00e7\u00e3o diversa \u00e9 o processo ideal para atrair novos talentos e se destacar no mercado. Portanto, \u00e9 o caminho que muitas empresas j\u00e1 est\u00e3o trilhando em seus recrutamentos. Ent\u00e3o, se quer ter uma firma mais inclusiva e plural, veja como aplicar essa iniciativa. Uma sele\u00e7\u00e3o diversa inclui quais grupos de minorias? Antes de entender [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2633,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,6],"tags":[288,88,788,796,793,797],"class_list":["post-2632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inclusao","category-rh-inclusivo","tag-diversidade-no-ambiente-de-trabalho","tag-inclusao","tag-recrutamento","tag-recrutamento-exclusivo-para-pessoas-com-deficiencia","tag-recrutar-pessoas-com-deficiencia","tag-selecao-diversa"],"_links":{"self":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts\/2632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/comments?post=2632"}],"version-history":[{"count":1,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts\/2632\/revisions"}],"predecessor-version":[{"id":2637,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts\/2632\/revisions\/2637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/media\/2633"}],"wp:attachment":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}