{"id":2580,"date":"2023-01-09T11:00:00","date_gmt":"2023-01-09T14:00:00","guid":{"rendered":"https:\/\/iigual.com.br\/blog\/?p=2580"},"modified":"2023-01-03T13:39:27","modified_gmt":"2023-01-03T16:39:27","slug":"beneficios-inclusivos","status":"publish","type":"post","link":"https:\/\/iigual.com.br\/blog\/beneficios-inclusivos\/","title":{"rendered":"O que s\u00e3o benef\u00edcios inclusivos? Conhe\u00e7a 4 regalias para oferecer a sua equipe"},"content":{"rendered":"\n<p>Oferecer <strong>benef\u00edcios inclusivos<\/strong> na empresa para a sua <a href=\"https:\/\/iigual.com.br\/blog\/2022\/07\/19\/equipe-de-trabalho-diversa\/\" target=\"_blank\" rel=\"noreferrer noopener\">equipe de trabalho diversa<\/a> \u00e9 essencial, a fim de elevar a satisfa\u00e7\u00e3o entre os funcion\u00e1rios, estabelecer uma nova cultura e reter talentos. Dessa forma, confira a import\u00e2ncia e ideias para incluir em seu neg\u00f3cio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Uma cultura inclusiva e benef\u00edcios inclusivos ajudam a atrair talentos?<\/h2>\n\n\n\n<p>Os<strong> benef\u00edcios inclusivos <\/strong>junto de uma cultura com foco na inclus\u00e3o ajuda a atrair talentos e tamb\u00e9m ret\u00ea-los. Ali\u00e1s, n\u00e3o adianta apenas falar sobre D&amp;I nas palestras da empresa, \u00e9 preciso a\u00e7\u00e3o e isso requer uma mudan\u00e7a real em seu neg\u00f3cio.<\/p>\n\n\n\n<p>A diversidade e a inclus\u00e3o devem fazer parte de um processo natural, n\u00e3o somente um <a href=\"https:\/\/www.suno.com.br\/artigos\/top-down\/\" target=\"_blank\" rel=\"noreferrer noopener\">top down<\/a> dos l\u00edderes. Pois, do contr\u00e1rio, adotar uma cultura mais inclusiva ser\u00e1 mais penoso e cheio de atritos.<\/p>\n\n\n\n<p>Uma das maneiras de colocar a D&amp;I em pr\u00e1tica, al\u00e9m da equidade de oportunidades, \u00e9 oferecer benef\u00edcios diversos. O que, com certeza, vai atrair e reter os talentos da sua empresa.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Beneficios-exclusivos-1024x683.jpg\" alt=\"Benef\u00edcios inclusivos: A imagem mostra dois homem, sendo um cadeirante, apertando as m\u00e3os. \" class=\"wp-image-2582\" width=\"1200\" height=\"800\" title=\"Dois homem apertando as m\u00e3os: Benef\u00edcios inclusivos\" srcset=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Beneficios-exclusivos-1024x683.jpg 1024w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Beneficios-exclusivos-300x200.jpg 300w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Beneficios-exclusivos-768x512.jpg 768w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Beneficios-exclusivos-750x500.jpg 750w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Beneficios-exclusivos-1140x760.jpg 1140w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Beneficios-exclusivos.jpg 1200w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">Financiar sess\u00f5es de terapia pode ser um dos benef\u00edcios inclusivos da sua empresa. Imagem de freepik no Freepik.<\/figcaption><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\">Tema importante entre a gera\u00e7\u00e3o Z&nbsp;<\/h3>\n\n\n\n<p>As pessoas nascidas a partir de 1995 s\u00e3o chamadas de gera\u00e7\u00e3o Z. O que vale destacar sobre eles \u00e9 que d\u00e3o valor \u00e0 diversidade de todos os jeitos. Afinal, a sociedade hoje \u00e9 cada vez mais inclusiva e plural.<\/p>\n\n\n\n<p>Por conta disso, logo que come\u00e7am a buscar um emprego, os profissionais da gera\u00e7\u00e3o Z d\u00e3o prefer\u00eancia \u00e0s empresas que investem na inclus\u00e3o e na diversidade. Portanto, s\u00e3o elas que conseguem os melhores talentos do mercado de trabalho.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Voc\u00ea sabe o que s\u00e3o benef\u00edcios inclusivos?<\/h2>\n\n\n\n<p>Os<strong> benef\u00edcios inclusivos <\/strong>s\u00e3o privil\u00e9gios que as empresas oferecem \u00e0s suas equipes que v\u00e3o al\u00e9m daqueles previstos por lei. Eles, portanto, s\u00e3o uma maneira de dar mais valor ao quadro de pessoal, al\u00e9m disso, busca promover mais bem-estar e seguran\u00e7a.<\/p>\n\n\n\n<p>Adotar esse tipo de a\u00e7\u00e3o \u00e9 vital e muitos neg\u00f3cios j\u00e1 chegaram a essa conclus\u00e3o. Isso \u00e9 o que mostra um estudo com o t\u00edtulo \u201c<a href=\"https:\/\/www.marsh.com\/mx\/services\/employee-health-benefits\/insights\/reinventing-benefits-latin-america-report.html\">Re<\/a><a href=\"https:\/\/www.marsh.com\/mx\/services\/employee-health-benefits\/insights\/reinventing-benefits-latin-america-report.html\" target=\"_blank\" rel=\"noreferrer noopener\">i<\/a><a href=\"https:\/\/www.marsh.com\/mx\/services\/employee-health-benefits\/insights\/reinventing-benefits-latin-america-report.html\">nventing Benefits<\/a>\u201d, com mais de 647 empresas de toda a Am\u00e9rica Latina.<\/p>\n\n\n\n<p>Nesta pesquisa, constatou-se que 82% de todas as firmas conseguem visualizar o qu\u00e3o essencial \u00e9 oferecer benef\u00edcios alternativos e inclusivos. Deste n\u00famero, vale citar, 51 das empresas s\u00e3o do Brasil.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Benef\u00edcios com base na inclus\u00e3o s\u00e3o um grande diferencial<\/h3>\n\n\n\n<p>As empresas de hoje precisam revisar os seus benef\u00edcios, bem como, os seus planos de sa\u00fade. Afinal, com o <a href=\"https:\/\/iigual.com.br\/blog\/2022\/10\/11\/ambiente-de-trabalho\/\" target=\"_blank\" rel=\"noreferrer noopener\">ambiente de trabalho<\/a> cada vez mais diverso, ter uma proposta de valor \u00e9 essencial para qualquer plano que busque investir na D&amp;I.\u00a0<\/p>\n\n\n\n<p>Sobre a pesquisa citada acima, 55% dos neg\u00f3cios alegaram que pretendem:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>ter pol\u00edticas de diversidade e inclus\u00e3o;<\/li>\n\n\n\n<li>criar programas com foco em combater ao preconceito;<\/li>\n\n\n\n<li>projetos para ajudar na carreira do seu quadro de pessoal.<\/li>\n<\/ul>\n\n\n\n<p>Cerca de 45% das empresas tamb\u00e9m expressaram a vontade de colocar em pr\u00e1tica <strong>benef\u00edcios inclusivos<\/strong> que possam lutar contra as desigualdades nas \u00e1reas da economia, educa\u00e7\u00e3o e social.<\/p>\n\n\n\n<p>Por \u00faltimo, vale dizer ainda que em 73% das corpora\u00e7\u00f5es participantes do estudo, um servi\u00e7o de telemedicina j\u00e1 estava dispon\u00edvel para os funcion\u00e1rios.<\/p>\n\n\n\n<p>Diante disso, veja quatro dicas de privil\u00e9gios que j\u00e1 est\u00e3o sendo aplicados nas rotinas das empresas e leve em conta alguns deles para agregar em seu pr\u00f3prio neg\u00f3cio.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">1 &#8211; Sa\u00fade mental<\/h4>\n\n\n\n<p>9 em cada 10 brasileiros atuantes no mercado de trabalho possuem algum sintoma de ansiedade, de acordo com a International Stress Management Association. Al\u00e9m disso, ainda segundo a ISMA, pelo menos 47% deles t\u00eam algum n\u00edvel de depress\u00e3o.<\/p>\n\n\n\n<p>N\u00e3o h\u00e1 d\u00favidas da import\u00e2ncia da sa\u00fade mental, ainda mais dentro do ambiente de trabalho. Portanto, muitas firmas t\u00eam investido em <strong>benef\u00edcios inclusivos<\/strong> para ajudar no bem-estar de suas equipes por meio do financiamento parcial ou integral de terapia.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">2 &#8211; Licen\u00e7as parentais<\/h4>\n\n\n\n<p>De acordo com a lei, as mulheres t\u00eam direito a 120 dias de licen\u00e7a maternidade e os homens, 5 dias. Mas, para as firmas que participam do Empresa Cidad\u00e3, programa do Governo Federal, esse prazo se estende para:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>180 dias para as mulheres;<\/li>\n\n\n\n<li>20 dias para os homens.<\/li>\n<\/ul>\n\n\n\n<p>Vale dizer ainda que muitas organiza\u00e7\u00f5es, de fato, prolongaram a licen\u00e7a parental, a fim de n\u00e3o refor\u00e7ar esse tipo de vi\u00e9s inconsciente de g\u00eanero.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"empresa cidad\u00e3 o por que devo me inscrever ou trabalhar numa empresa  assim\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/XWyCKRSVvBU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\">Exemplo real de sucesso<\/h5>\n\n\n\n<p>O Botic\u00e1rio \u00e9 um exemplo de empresa que oferece <strong>benef\u00edcios inclusivos<\/strong> referentes a licen\u00e7a parental. Isso porque, ela concede 120 dias para:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>homens;<\/li>\n\n\n\n<li>mulheres;<\/li>\n\n\n\n<li>pais de filhos adotivos;<\/li>\n\n\n\n<li>casais homoafetivos.<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Beneficios-exclusivos-2-1024x683.jpg\" alt=\"Benef\u00edcios inclusivos: A imagem mostra uma pessoa cadeirante apresentando dados e resultados da empresa para o chefe. \" class=\"wp-image-2583\" width=\"1200\" height=\"800\" title=\"Pessoa cadeirante apresentando dados: Benef\u00edcios inclusivos\" srcset=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Beneficios-exclusivos-2-1024x683.jpg 1024w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Beneficios-exclusivos-2-300x200.jpg 300w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Beneficios-exclusivos-2-768x512.jpg 768w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Beneficios-exclusivos-2-750x500.jpg 750w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Beneficios-exclusivos-2-1140x760.jpg 1140w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2023\/01\/Beneficios-exclusivos-2.jpg 1200w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">Um dos benef\u00edcios inclusivos \u00e9 oferecer apoio financeiro \u00e0s pessoas com defici\u00eancia da empresa na quest\u00e3o da acessibilidade. Imagem de freepik no Freepik<\/figcaption><\/figure>\n<\/div>\n\n\n<h4 class=\"wp-block-heading\">3 &#8211; Apoio na quest\u00e3o da acessibilidade<\/h4>\n\n\n\n<p>Romeu Sassaki estabelece que existem seis tipos de <a href=\"https:\/\/iigual.com.br\/blog\/2022\/10\/12\/acessibilidade-5\/\" target=\"_blank\" rel=\"noreferrer noopener\">acessibilidade<\/a>, dentre elas, vale mencionar:<br><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>metodol\u00f3gica;<\/li>\n\n\n\n<li>program\u00e1tica;<\/li>\n\n\n\n<li>arquitet\u00f4nica;<\/li>\n\n\n\n<li>comunicacional;<\/li>\n\n\n\n<li>instrumental;<\/li>\n\n\n\n<li>atitudinal.<\/li>\n<\/ul>\n\n\n\n<p>A arquitet\u00f4nica, por exemplo, se refere \u00e0 infraestrutura, enquanto a instrumental, por outro lado, diz respeito a adaptar o ambiente com os aparelhos mais adequados a cada necessidade.<\/p>\n\n\n\n<p>Todas essas mudan\u00e7as possuem um pre\u00e7o alto para as pessoas com defici\u00eancias. Desse modo, as empresas devem avaliar as demandas desse grupo em sua equipe e oferecer, como <strong>benef\u00edcios inclusivos<\/strong>, um apoio financeiro para essas adapta\u00e7\u00f5es em suas rotinas.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">4 &#8211; Experi\u00eancias&nbsp;<\/h4>\n\n\n\n<p>Investir em novas experi\u00eancias \u00e9 importante para o seu quadro de pessoal. Portanto, pode ser interessante estimular e ainda proporcionar a\u00e7\u00f5es como:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>idas a museus;<\/li>\n\n\n\n<li>projetos sociais;<\/li>\n\n\n\n<li>voluntariado.<\/li>\n<\/ul>\n\n\n\n<p>Os l\u00edderes e gestores tamb\u00e9m podem criar as suas pr\u00f3prias experi\u00eancias. Por exemplo, criar um evento onde os seus colaboradores que possuem defici\u00eancia visual podem guiar os colegas e clientes por salas escuras.<\/p>\n\n\n\n<p>Com isso, \u00e9 poss\u00edvel criar esse tipo de ambiente com elementos que estimulam os outros sentidos por meio de sons, texturas e cheiros.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Os benef\u00edcios inclusivos j\u00e1 s\u00e3o uma realidade nas empresas?<\/h2>\n\n\n\n<p>Marcas como O Botic\u00e1rio j\u00e1 aplicam <strong>benef\u00edcios inclusivos <\/strong>e depois desse artigo, o seu neg\u00f3cio tamb\u00e9m pode fazer o mesmo<strong>.<\/strong> A fim de atrair e tamb\u00e9m reter os melhores talentos do mercado de trabalho.<\/p>\n\n\n\n<p>\u00c9 essencial para estimular o seu quadro de pessoal e tornar cada um dos membros do seu time mais produtivos. Ent\u00e3o, com a sociedade mais plural e diversa, com o tempo essa tem\u00e1tica ser\u00e1 mais abordada e posta em pr\u00e1tica por empresas que desejam o sucesso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oferecer benef\u00edcios inclusivos na empresa para a sua equipe de trabalho diversa \u00e9 essencial, a fim de elevar a satisfa\u00e7\u00e3o entre os funcion\u00e1rios, estabelecer uma nova cultura e reter talentos. Dessa forma, confira a import\u00e2ncia e ideias para incluir em seu neg\u00f3cio. Uma cultura inclusiva e benef\u00edcios inclusivos ajudam a atrair talentos? Os benef\u00edcios inclusivos [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2587,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,6],"tags":[781,88,782,780,778,779],"class_list":["post-2580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inclusao","category-rh-inclusivo","tag-beneficios","tag-inclusao","tag-inclusivos","tag-oferecer-beneficios-inclusivos-na-empresa","tag-privilegios-que-as-empresas-oferecem-as-suas-equipes-que-vao-alem-daqueles-previstos-por-lei","tag-reter-talentos"],"_links":{"self":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts\/2580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/comments?post=2580"}],"version-history":[{"count":1,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts\/2580\/revisions"}],"predecessor-version":[{"id":2588,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts\/2580\/revisions\/2588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/media\/2587"}],"wp:attachment":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}