{"id":2529,"date":"2022-12-23T12:54:56","date_gmt":"2022-12-23T15:54:56","guid":{"rendered":"https:\/\/iigual.com.br\/blog\/?p=2529"},"modified":"2022-12-23T12:54:57","modified_gmt":"2022-12-23T15:54:57","slug":"pessoas-com-deficiencia-26","status":"publish","type":"post","link":"https:\/\/iigual.com.br\/blog\/pessoas-com-deficiencia-26\/","title":{"rendered":"O que n\u00e3o fazer na hora de recrutar pessoas com defici\u00eancia para trabalhar na sua empresa?"},"content":{"rendered":"\n<p>Contratar<strong> pessoas com defici\u00eancia<\/strong> \u00e9 um passo muito importante que uma empresa deve fazer para se tornar ter uma <a href=\"https:\/\/iigual.com.br\/blog\/2022\/11\/25\/gestao-inclusiva-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">gest\u00e3o inclusiva<\/a>. Mas, h\u00e1 algumas dicas sobre erros que n\u00e3o deve cometer no <a href=\"https:\/\/santandernegocioseempresas.com.br\/conhecimento\/gestao-de-pessoas\/processo-seletivo-pcd\/\" target=\"_blank\" rel=\"noreferrer noopener\">processo seletivo<\/a>, ent\u00e3o leia este artigo com aten\u00e7\u00e3o e saiba quais s\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que n\u00e3o fazer na hora de contratar pessoas com defici\u00eancia?<\/h2>\n\n\n\n<p>Uma das quest\u00f5es principais para o processo de contratar uma pessoa que tenha algum <strong>tipo de defici\u00eancia<\/strong> \u00e9 n\u00e3o pensar apenas que seja obriga\u00e7\u00e3o legal. Afinal, tamb\u00e9m se trata de profissionais que s\u00e3o qualificados para o cargo na qual a empresa oferece a vaga.<\/p>\n\n\n\n<p>Nesse contexto, h\u00e1 mais aspectos que s\u00e3o importantes destacar para n\u00e3o cometer erros nessa fase, como:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>n\u00e3o focar nas cotas;<\/li>\n\n\n\n<li>contratar e incluir s\u00e3o diferentes;<\/li>\n\n\n\n<li>flexibilizar o tipo de perfil;<\/li>\n\n\n\n<li>generaliza\u00e7\u00e3o;<\/li>\n\n\n\n<li>rotula\u00e7\u00e3o.<\/li>\n<\/ul>\n\n\n\n<p>Esses pontos s\u00e3o vitais para a etapa recrutamento de <strong>pessoas com defici\u00eancia<\/strong>. Por isso, este artigo ir\u00e1 mostrar cada um deles de maneira mais a fundo para ajudar voc\u00ea com esse processo. Ent\u00e3o, leia com aten\u00e7\u00e3o, porque pode fazer toda a diferen\u00e7a na hora de contratar.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2022\/12\/Pessoas-com-deficiencia-1.jpg\" alt=\"Homem em cadeira de rodas divide mesa em ambiente de trabalho com duas mulheres\" class=\"wp-image-2533\" srcset=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2022\/12\/Pessoas-com-deficiencia-1.jpg 1200w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2022\/12\/Pessoas-com-deficiencia-1-300x200.jpg 300w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2022\/12\/Pessoas-com-deficiencia-1-1024x683.jpg 1024w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2022\/12\/Pessoas-com-deficiencia-1-768x512.jpg 768w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2022\/12\/Pessoas-com-deficiencia-1-750x500.jpg 750w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2022\/12\/Pessoas-com-deficiencia-1-1140x760.jpg 1140w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">Recrutar pessoas com defici\u00eancia \u00e9 vital para uma empresa se tornar inclusiva. Imagem de Ivan Samkov no Pexels.<\/figcaption><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\">N\u00e3o foque na cotas para pessoas com defici\u00eancia<\/h3>\n\n\n\n<p>\u00c9 um fato que muitas empresas contratam apenas porque \u00e9 lei, embora seja fundamental, mas fazer por obriga\u00e7\u00e3o \u00e9 um grande erro. Visto que, ao contratar uma<strong> PCD<\/strong>, a pauta da inclus\u00e3o deve ser de acordo com a qualidade do profissional,e suas habilidades.<\/p>\n\n\n\n<p>Com isso, \u00e9 importante que o recrutador n\u00e3o deixe que as limita\u00e7\u00f5es f\u00edsicas de uma pessoa sejam crit\u00e9rio para preencher uma vaga.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Contratar e inclus\u00e3o s\u00e3o diferentes<\/h3>\n\n\n\n<p>N\u00e3o contrate apenas para fazer n\u00famero na empresa, uma <strong>pessoa com limita\u00e7\u00f5es f\u00edsicas <\/strong>tamb\u00e9m pode agregar no crescimento do neg\u00f3cio. Ao passo que, recrutar aqueles que s\u00e3o qualificados para os cargos \u00e9 o ideal.&nbsp;<\/p>\n\n\n\n<p>Vale lembrar que a inclus\u00e3o est\u00e1 presente em oferecer chances iguais para todos, de forma que ir\u00e3o ampliar suas fun\u00e7\u00f5es e responsabilidades.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Flexibilize o perfil das pessoas com defici\u00eancia<\/h3>\n\n\n\n<p>Diminuir algumas exig\u00eancias n\u00e3o t\u00e3o importantes \u00e9 um fator que ir\u00e1 ajudar no processo. Isso far\u00e1 com que amplie a possibilidade de contratar as <strong>pessoas com defici\u00eancia<\/strong> de forma mais eficiente, portanto, avalie esse cen\u00e1rio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">N\u00e3o generalizar<\/h3>\n\n\n\n<p>Quando voc\u00ea entende que todos s\u00e3o iguais, mesmo as pessoas que t\u00eam defici\u00eancia, o processo para recrutar ser\u00e1 mais assertivo. Afinal, embora haja aqueles com condi\u00e7\u00f5es iguais, as habilidades que possuem s\u00e3o diferentes, bem como o talento e conhecimento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sem rotular<\/h3>\n\n\n\n<p>Enxergar as pessoas al\u00e9m da defici\u00eancia \u00e9 vital para<strong> inclus\u00e3o social<\/strong> dentro de uma empresa. Ao passo que, na entrevista de um candidato, n\u00e3o se atente para aspectos que o possam diferenciar dos demais, apenas na capacidade para a vaga.&nbsp;<\/p>\n\n\n\n<p>Outro ponto que vale destacar \u00e9 n\u00e3o usar o termo PCD ou fazer alguma men\u00e7\u00e3o \u00e0 sua defici\u00eancia se n\u00e3o for relevante, deixe-o \u00e0 vontade para falar.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"Inclus\u00e3o de pessoas com defici\u00eancia no mercado de trabalho - Conex\u00e3o Futura - Canal Futura\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/-z7xgJveJOo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">O que diz a legisla\u00e7\u00e3o sobre contratar pessoas com defici\u00eancia?<\/h2>\n\n\n\n<p>Um dos principais aspectos sobre esse assunto \u00e9 em rela\u00e7\u00e3o ao n\u00famero de empregados que uma empresa deve possuir no quadro de funcion\u00e1rios. De modo que, se ela possui entre 100 e 200, pelo menos 2% deles devem ser de <strong>pessoas com defici\u00eancia<\/strong>.&nbsp;<\/p>\n\n\n\n<p>Quanto maior for a quantidade de colaboradores, por sua vez, aumenta tamb\u00e9m a porcentagem, por exemplo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>201 a 500, 3%;<\/li>\n\n\n\n<li>501 a 1000, 4%;<\/li>\n\n\n\n<li>A partir de 1001, sobe para 5%.<\/li>\n<\/ul>\n\n\n\n<p>Tudo isso \u00e9 de acordo com a lei, que estabelece um n\u00famero m\u00ednimo para que uma firma possa respeitar seu quadro de funcion\u00e1rios. Contudo, vale destacar \u00e9 a respeito de demiss\u00f5es que s\u00f3 podem ser feitas quando h\u00e1 outra pessoa com defici\u00eancia para a vaga.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como conduzir o processo de contratar pessoas com defici\u00eancia?<\/h2>\n\n\n\n<p>N\u00e3o basta s\u00f3 contratar os <strong>candidatos com defici\u00eancia<\/strong>, promover uma <a href=\"https:\/\/www.pontotel.com.br\/inclusao-social-nas-empresas\/\" target=\"_blank\" rel=\"noreferrer noopener\">inclus\u00e3o social<\/a> no trabalho tamb\u00e9m \u00e9 parte vital do processo. Al\u00e9m disso, conter pol\u00edticas para contemplar as diferen\u00e7as tamb\u00e9m \u00e9 importante antes mesmo de recrutar, ent\u00e3o, busque manter a equipe bem informada sobre o tema.\u00a0<\/p>\n\n\n\n<p>H\u00e1 outros pontos que fazem parte da etapa de condu\u00e7\u00e3o do processo de contrata\u00e7\u00e3o, como se ver\u00e1 na sequ\u00eancia.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2022\/12\/Pessoas-com-deficiencia-2.jpg\" alt=\"Homem em cadeira de rodas em reuni\u00e3o de trabalho com mulheres\" class=\"wp-image-2534\" srcset=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2022\/12\/Pessoas-com-deficiencia-2.jpg 1200w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2022\/12\/Pessoas-com-deficiencia-2-300x200.jpg 300w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2022\/12\/Pessoas-com-deficiencia-2-1024x683.jpg 1024w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2022\/12\/Pessoas-com-deficiencia-2-768x512.jpg 768w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2022\/12\/Pessoas-com-deficiencia-2-750x500.jpg 750w, https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2022\/12\/Pessoas-com-deficiencia-2-1140x760.jpg 1140w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">Ter pessoas com defici\u00eancia no trabalho torna o ambiente mais inclusivo e produtivo. Imagem de Kampus Production no Pexels.<\/figcaption><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\">Divulgue as vagas da forma certa<\/h3>\n\n\n\n<p>Essa etapa \u00e9 mais pr\u00e1tica do processo de sele\u00e7\u00e3o, de modo que, fazer a divulga\u00e7\u00e3o de forma mais direta \u00e9 o ideal. Ent\u00e3o, no caso das vagas para deficientes, deixe isso de forma clara na descri\u00e7\u00e3o, bem como anunciar em canais para esse p\u00fablico.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Consultoria adequada para contratar pessoas com defici\u00eancia<\/h3>\n\n\n\n<p>Uma consultoria especializada ajudar\u00e1 a recrutar <strong>pessoas com necessidades especiais<\/strong>, de uma forma bem mais assertiva e r\u00e1pida. Al\u00e9m disso, h\u00e1 muitas empresas que contam com um grande banco de talentos, bem como fazer a sele\u00e7\u00e3o dos candidatos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tenha aten\u00e7\u00e3o no processo seletivo<\/h3>\n\n\n\n<p>Acompanhe de perto o processo seletivo dos candidatos para que tenha dados mais precisos sobre cada um deles e fazer a melhor escolha. Todavia, n\u00e3o os subestime, considere todos os crit\u00e9rios t\u00e9cnicos e os de comportamento, tamb\u00e9m deixe claro as exig\u00eancias para definir a vaga. Por fim, \u00e9 vital n\u00e3o fazer men\u00e7\u00e3o \u00e0 sua defici\u00eancia nessa etapa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Por que uma empresa deve contratar pessoas com defici\u00eancia?<\/h2>\n\n\n\n<p>Embora seja estabelecido por lei, contratar <strong>pessoas com defici\u00eancia<\/strong> para a sua empresa vai muito al\u00e9m do dever legal, a torna inclusiva tamb\u00e9m. Como resultado disso, a sua firma pode ter uma s\u00e9rie de benef\u00edcios, por exemplo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>fazer com que todos os colaboradores se sintam importante;<\/li>\n\n\n\n<li>uma marca empregadora positiva;<\/li>\n\n\n\n<li>maior chance de acertar em bons profissionais;;<\/li>\n\n\n\n<li>equipe mais produtiva.<\/li>\n<\/ul>\n\n\n\n<p>Tudo isso ir\u00e1 ampliar os horizontes para que cada vez mais candidatos de qualidade se interessem por trabalhar na sua empresa. Afinal, ter uma marca que seja inclusiva atrai os olhos dos investidores e gera uma boa reputa\u00e7\u00e3o para o seu nome.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"Inclus\u00e3o da pessoa com defici\u00eancia no mercado de trabalho\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/AW8MAzRpzJI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Contratar pessoas com defici\u00eancia melhora a imagem da empresa?<\/h2>\n\n\n\n<p>As <strong>pessoas com defici\u00eancia<\/strong> ainda s\u00e3o minorias no mercado de trabalho e h\u00e1 muita desconfian\u00e7a sobre suas capacidades de ocupar grandes cargos e vagas. Mas, para empresas que j\u00e1 contam com eles em seu quadros t\u00eam uma s\u00e9rie de vantagens:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/iigual.com.br\/blog\/2022\/10\/11\/ambiente-de-trabalho\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ambiente de trabalho<\/a> sem preconceito;<\/li>\n\n\n\n<li>Trabalho mais produtivo;<\/li>\n\n\n\n<li>Marca reconhecida por ser inclusiva;<\/li>\n<\/ul>\n\n\n\n<p>Entre muitos outros, como o valor que os membros de todo o corpo da firma d\u00e3o a ela, o que contribui para um clima positivo. Por fim, aqueles com defici\u00eancia ir\u00e3o se sentir cada vez mais importantes dentro da equipe, porque s\u00e3o tratados igual aos demais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contratar pessoas com defici\u00eancia \u00e9 um passo muito importante que uma empresa deve fazer para se tornar ter uma gest\u00e3o inclusiva. Mas, h\u00e1 algumas dicas sobre erros que n\u00e3o deve cometer no processo seletivo, ent\u00e3o leia este artigo com aten\u00e7\u00e3o e saiba quais s\u00e3o. O que n\u00e3o fazer na hora de contratar pessoas com defici\u00eancia? [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2531,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,6],"tags":[732,279,165,731,101,733,730],"class_list":["post-2529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inclusao","category-rh-inclusivo","tag-candidatos-com-deficiencia-2","tag-inclusao-social","tag-pcd","tag-pessoa-com-limitacoes-fisicas","tag-pessoas-com-deficiencia","tag-pessoas-com-necessidades-especiais","tag-tipo-de-deficiencia"],"_links":{"self":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts\/2529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/comments?post=2529"}],"version-history":[{"count":1,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts\/2529\/revisions"}],"predecessor-version":[{"id":2535,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts\/2529\/revisions\/2535"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/media\/2531"}],"wp:attachment":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}