{"id":132,"date":"2020-05-06T18:05:29","date_gmt":"2020-05-06T21:05:29","guid":{"rendered":"http:\/\/iigual.com.br\/blog\/?p=132"},"modified":"2021-02-03T18:18:02","modified_gmt":"2021-02-03T18:18:02","slug":"inclusao-digital-por-que-voce-precisa-pensar-nisso","status":"publish","type":"post","link":"https:\/\/iigual.com.br\/blog\/inclusao-digital-por-que-voce-precisa-pensar-nisso\/","title":{"rendered":"Inclus\u00e3o Digital: por que voc\u00ea precisa pensar nisso?"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/iigual.com.br\/blog\/wp-content\/uploads\/2020\/05\/giphy-2-1.gif\" alt=\"\" class=\"wp-image-378\"\/><\/figure>\n\n\n\n<p>Voc\u00ea sabe o que \u00e9 inclus\u00e3o ou acessibilidade digital?<\/p>\n\n\n\n<p>Como j\u00e1 falamos antes, acessibilidade digital \u00e9 o conjunto de recursos que podem ser instalados em seus canais digitais, para garantir que pessoas com baixo letramento, idosos e pessoas com defici\u00eancias possam entender todas as informa\u00e7\u00f5es e navegar pelo site sem ajuda de terceiros.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Ainda pensando em inclus\u00e3o digital, hoje vamos trazer alguns motivos para voc\u00ea come\u00e7ar a se preocupar com a acessibilidade nos seus canais, e aplicar as medidas no seu site:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Diversificar o p\u00fablico: <\/strong>um dos maiores ganhos ao promover a inclus\u00e3o digital, \u00e9 da sua empresa. Isso porque seu site poder\u00e1 ser acessado por mais pessoas. Pessoas com defici\u00eancia poder\u00e3o ter acesso ao seu conte\u00fado ou servi\u00e7o. Al\u00e9m disso, sua empresa ainda ganha a confian\u00e7a de quem se preocupa com as pautas de inclus\u00e3o.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Cumprir seu papel social:<\/strong> Voc\u00ea j\u00e1 pensou em como a sua empresa tem cumprido pap\u00e9is sociais, e em como isso agrega valor ao seu produto? Tamb\u00e9m gera sentimento de prop\u00f3sito nos colaboradores e clientes. Que se tornam simpatizantes da sua marca, porque tem um papel social.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Auxiliar na inclus\u00e3o digital de toda a popula\u00e7\u00e3o:<\/strong> Como j\u00e1 dissemos, a inclus\u00e3o digital tem um objetivo: tornar a web um ambiente para todos. Tanto para a pessoa com alguma defici\u00eancia, quanto para aquele que teve baixo letramento, por exemplo. Ofere\u00e7a oportunidades iguais e descubra um p\u00fablico que, infelizmente, muitas vezes \u00e9 ignorado.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Cumprimento da legisla\u00e7\u00e3o: <\/strong>Est\u00e1 decretado por lei (13.146) que a web seja acess\u00edvel. O acesso a informa\u00e7\u00e3o \u00e9 para todos: Voc\u00ea consegue imaginar sua vida sem acesso \u00e0 not\u00edcias, sem compras online, sem chamar aquele carro pelo aplicativo ou pedir a comida que est\u00e1 com vontade, e receber sem sair de casa? Todas essas coisas s\u00e3o tecnologias recentes, mas ainda assim, fazem parte de nossas vidas, tornar o ambiente virtual acess\u00edvel \u00e9 permitir que essas tecnologias alcancem mais pessoas, melhorando a vida de muitos.<\/li><\/ul>\n\n\n\n<p>J\u00e1 deu para perceber o quanto \u00e9 importante permitir o acesso de todos aos canais digitais da sua empresa, n\u00e3o \u00e9? Caso precise, voc\u00ea pode aprender a tornar seu site acess\u00edvel.<\/p>\n\n\n\n<p>Sabe mais algum motivo para priorizar a acessibilidade na web? Conte para n\u00f3s nos coment\u00e1rios!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea sabe o que \u00e9 inclus\u00e3o ou acessibilidade digital? Como j\u00e1 falamos antes, acessibilidade digital \u00e9 o conjunto de recursos que podem ser instalados em seus canais digitais, para garantir que pessoas com baixo letramento, idosos e pessoas com defici\u00eancias possam entender todas as informa\u00e7\u00f5es e navegar pelo site sem ajuda de terceiros. Ainda pensando [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":499,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[98,99],"class_list":["post-132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-web-acessivel","tag-iigual-inclusao","tag-web-acessivel"],"_links":{"self":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts\/132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/comments?post=132"}],"version-history":[{"count":1,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts\/132\/revisions"}],"predecessor-version":[{"id":445,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/posts\/132\/revisions\/445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/media\/499"}],"wp:attachment":[{"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/media?parent=132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/categories?post=132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iigual.com.br\/blog\/wp-json\/wp\/v2\/tags?post=132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}